{"id":21639,"date":"2026-06-10T14:28:13","date_gmt":"2026-06-10T18:28:13","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=21639"},"modified":"2026-06-11T14:35:21","modified_gmt":"2026-06-11T18:35:21","slug":"periode-des-questions-le-conseil-consultatif-sur-les-droits-legalite-et-linclusion-3","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/periode-de-questions\/periode-des-questions-le-conseil-consultatif-sur-les-droits-legalite-et-linclusion-3\/","title":{"rendered":"P\u00e9riode des questions : Le Conseil consultatif sur les droits, l\u2019\u00e9galit\u00e9 et l\u2019inclusion"},"content":{"rendered":"<p><iframe title=\"La s\u00e9n. Gerba pose des questions sur le Conseil consultatif sur les droits, l\u2019\u00e9galit\u00e9 et l\u2019inclusion\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/TzynQAu8h8s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Amina Gerba :<span>\u00a0<\/span><\/b>S\u00e9nateur Moreau, ma question fait suite \u00e0 celles qui ont \u00e9t\u00e9 pos\u00e9es par les s\u00e9natrices Senior et Bernard et elle concerne le Conseil consultatif sur les droits, l\u2019\u00e9galit\u00e9 et l\u2019inclusion. Comme vous le savez, la population canadienne compte 4,3\u00a0% de personnes issues des communaut\u00e9s noires. Pourtant, ces derni\u00e8res repr\u00e9sentent 37\u00a0% des crimes haineux d\u00e9clar\u00e9s par la police. Comment expliquer que le gouvernement mette en place un conseil qui n\u2019inclut aucune repr\u00e9sentation issue des communaut\u00e9s noires?<\/p>\n<p><b>L\u2019honorable Pierre Moreau (repr\u00e9sentant du gouvernement au S\u00e9nat) :<span>\u00a0<\/span><\/b>Je vous remercie de soulever la question, s\u00e9natrice Gerba. J\u2019ai qualifi\u00e9 ce sujet de \u00ab fort important \u00bb quand les s\u00e9natrices Bernard et Senior ont parl\u00e9 de la question\u00a0\u2014 si important que j\u2019ai pris la peine, comme repr\u00e9sentant du S\u00e9nat aupr\u00e8s du gouvernement, de soulever la question aupr\u00e8s du bureau du premier ministre. Je peux d\u2019ailleurs vous assurer qu\u2019il n\u2019y a aucune arri\u00e8re\u2011pens\u00e9e ou discrimination dans la d\u00e9cision qui a \u00e9t\u00e9 prise.<\/p>\n<p>Aujourd\u2019hui, je suis en mesure de vous dire que la composition du comit\u00e9 n\u2019est pas compl\u00e9t\u00e9e, que tous les membres du conseil n\u2019ont pas encore \u00e9t\u00e9 annonc\u00e9s et que d\u2019autres nominations seront faites dans les semaines \u00e0 venir, en tenant compte des remarques que j\u2019ai transmises au bureau du premier ministre par votre interm\u00e9diaire et par l\u2019interm\u00e9diaire des s\u00e9natrices Bernard et Senior, bien entendu.<\/p>\n<p><b>Son Honneur la Pr\u00e9sidente :<span>\u00a0<\/span><\/b>S\u00e9natrice Gerba, avez-vous une autre question?<\/p>\n<p><b>La s\u00e9natrice Gerba :<span>\u00a0<\/span><\/b>Je pense que cela r\u00e9pond bien \u00e0 ma question. Nous avons bien h\u00e2te de conna\u00eetre la prochaine constitution de ce conseil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Amina Gerba :\u00a0S\u00e9nateur Moreau, ma question fait suite \u00e0 celles qui ont \u00e9t\u00e9 pos\u00e9es par les s\u00e9natrices Senior et Bernard et elle concerne le Conseil consultatif sur les droits, l\u2019\u00e9galit\u00e9 et l\u2019inclusion. Comme vous le savez, la population canadienne compte 4,3\u00a0% de personnes issues des communaut\u00e9s noires. Pourtant, ces derni\u00e8res repr\u00e9sentent 37\u00a0% des crimes&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[97],"tags":[],"senator_posts":[117],"class_list":["post-21639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-periode-de-questions","senator_posts-l-hon-amina-gerba"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/21639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=21639"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/21639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/1916"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=21639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=21639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=21639"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=21639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}