{"id":20963,"date":"2026-04-15T15:50:15","date_gmt":"2026-04-15T19:50:15","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=20963"},"modified":"2026-04-17T15:52:23","modified_gmt":"2026-04-17T19:52:23","slug":"lhonorable-peter-harder-c-p-la-collection-dobjets-dart-et-dartefacts","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/declarations\/lhonorable-peter-harder-c-p-la-collection-dobjets-dart-et-dartefacts\/","title":{"rendered":"L\u2019honorable Peter Harder, C.P.\u2014La collection d\u2019objets d\u2019art et d\u2019art\u00e9facts"},"content":{"rendered":"<p><iframe title=\"S\u00e9nateur Cardozo parle de l\u2019hon. Peter Harder &amp; la collection d\u2019objets d\u2019art &amp; d\u2019art\u00e9facts du S\u00e9nat\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/LL7RNzI2i5c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Andrew Cardozo :<span>\u00a0<\/span><\/b>Honorables s\u00e9nateurs, j\u2019ai une bonne nouvelle \u00e0 vous annoncer. En ma qualit\u00e9 de pr\u00e9sident du Groupe de travail consultatif sur les \u0153uvres d\u2019art et le patrimoine du S\u00e9nat, je suis tr\u00e8s heureux de vous parler d\u2019un ajout important \u00e0 notre collection\u00a0: une maquette en bronze de Sa Majest\u00e9 la reine Elizabeth II, g\u00e9n\u00e9reusement offerte au S\u00e9nat par notre coll\u00e8gue, le s\u00e9nateur Peter Harder.<\/p>\n<p><b>Des voix :<span>\u00a0<\/span><\/b>Bravo!<\/p>\n<p><b>Le s\u00e9nateur Cardozo :<span>\u00a0<\/span><\/b>J\u2019esp\u00e8re que ces longs applaudissements ne vont pas empi\u00e9ter sur mon temps de parole.<\/p>\n<p>Cette \u0153uvre remarquable, r\u00e9alis\u00e9e par la c\u00e9l\u00e8bre artiste ontarienne Ruth Abernethy, repr\u00e9sente la reine Elizabeth II assise sur le tr\u00f4ne du monarque dans la salle du S\u00e9nat \u00e0 l\u2019\u00e9difice du Centre. Elle rend bien hommage aux liens durables de la reine avec le Canada et le Parlement.<\/p>\n<p>Inspir\u00e9e de la lecture du discours du Tr\u00f4ne en 1977, la maquette montre la reine tenant une branche compos\u00e9e de 13 feuilles d\u2019\u00e9rable, qui symbolisent les provinces et les territoires du Canada. Il s\u2019agit de l\u2019une des deux r\u00e9pliques \u00e0 petite \u00e9chelle du monument comm\u00e9moratif plus imposant, d\u2019environ sept m\u00e8tres de haut, qui a \u00e9t\u00e9 d\u00e9voil\u00e9 devant l\u2019Assembl\u00e9e l\u00e9gislative de l\u2019Ontario en 2023.<\/p>\n<p>La sculpture porte \u00e9galement une citation tir\u00e9e de son discours, dans lequel elle a d\u00e9clar\u00e9\u00a0: \u00ab Je veux r\u00e9it\u00e9rer mon engagement envers ce peuple et ce pays que je suis fi\u00e8re de servir. \u00bb<\/p>\n<p>Ce g\u00e9n\u00e9reux don du s\u00e9nateur Harder \u00e0 la collection permanente du S\u00e9nat est fait en m\u00e9moire de sa d\u00e9funte \u00e9pouse, Molly Seon. Permettez-moi de dire quelques mots sur chacun d\u2019eux.<\/p>\n<p>Le s\u00e9nateur Harder a jou\u00e9 un r\u00f4le de premier plan dans l\u2019histoire du S\u00e9nat du Canada, notamment gr\u00e2ce \u00e0 son travail remarquable en tant que premier repr\u00e9sentant ind\u00e9pendant du gouvernement au S\u00e9nat et en tant que figure de proue qui nous a habilement guid\u00e9s dans le processus de renouvellement d\u2019un S\u00e9nat moderne et ind\u00e9pendant entre 2016 et 2020.<\/p>\n<p>Comme me l\u2019a dit r\u00e9cemment l\u2019huissier du b\u00e2ton noir\u00a0:<\/p>\n<p style=\"padding-left: 40px;\">Molly Seon \u00e9tait une monarchiste dans l\u2019\u00e2me. Elle vouait un amour et une affection immenses \u00e0 Sa Majest\u00e9 la reine et \u00e0 tout ce qui touchait \u00e0 la royaut\u00e9. Elle avait tant appr\u00e9ci\u00e9 sa visite au ch\u00e2teau de Windsor et aux \u00e9curies royales. La d\u00e9cision du s\u00e9nateur Harder d\u2019honorer Molly de cette mani\u00e8re pour comm\u00e9morer le discours du Tr\u00f4ne prononc\u00e9 par le roi en\u00a0mai\u00a0dernier rev\u00eat, en effet, une importance consid\u00e9rable pour les g\u00e9n\u00e9rations \u00e0 venir.<\/p>\n[<i>Fran\u00e7ais<\/i>]\n<p>Chers coll\u00e8gues, cette maquette vient enrichir la collection permanente d\u2019\u0153uvres d\u2019art et de biens patrimoniaux du S\u00e9nat et vient ainsi compl\u00e9ter notre patrimoine culturel et historique.<\/p>\n[<i>Traduction<\/i>]\n<p>Je vous invite \u00e0 prendre un moment pour admirer cette \u0153uvre exquise et \u00e0 participer \u00e0 l\u2019activit\u00e9 organis\u00e9e par la Pr\u00e9sidente Gagn\u00e9 \u00e0 16 heures pour souligner ce don.<\/p>\n<p>Au nom de tous les s\u00e9nateurs, je tiens \u00e0 remercier chaleureusement le s\u00e9nateur Harder pour ce cadeau extraordinaire et pour l\u2019esprit dans lequel il a servi cette institution.<\/p>\n<p><b>Des voix :<span>\u00a0<\/span><\/b>Bravo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Andrew Cardozo :\u00a0Honorables s\u00e9nateurs, j\u2019ai une bonne nouvelle \u00e0 vous annoncer. En ma qualit\u00e9 de pr\u00e9sident du Groupe de travail consultatif sur les \u0153uvres d\u2019art et le patrimoine du S\u00e9nat, je suis tr\u00e8s heureux de vous parler d\u2019un ajout important \u00e0 notre collection\u00a0: une maquette en bronze de Sa Majest\u00e9 la reine Elizabeth II,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[99],"tags":[],"senator_posts":[178],"class_list":["post-20963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-declarations","senator_posts-l-hon-andrew-cardozo"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=20963"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/2028"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=20963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=20963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=20963"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=20963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}