{"id":20951,"date":"2026-04-14T14:22:47","date_gmt":"2026-04-14T18:22:47","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=20951"},"modified":"2026-04-16T14:27:18","modified_gmt":"2026-04-16T18:27:18","slug":"la-senatrice-gerba-interroge-le-ministre-de-lintelligence-artificielle-et-de-linnovation-numerique-en-comite-plenier","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/la-senatrice-gerba-interroge-le-ministre-de-lintelligence-artificielle-et-de-linnovation-numerique-en-comite-plenier\/","title":{"rendered":"La s\u00e9natrice Gerba interroge le ministre de l\u2019Intelligence artificielle et de l\u2019Innovation num\u00e9rique en comit\u00e9 pl\u00e9nier"},"content":{"rendered":"<p><iframe title=\"La s\u00e9natrice Gerba interroge le ministre Solomon en comit\u00e9 pl\u00e9nier - 14 avril 2026 (FR)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/_DlTkmSFhII?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><em>Le S\u00e9nat s\u2019est form\u00e9 en comit\u00e9 pl\u00e9nier afin de recevoir l\u2019honorable Evan Solomon, c.p., d\u00e9put\u00e9, ministre de l\u2019Intelligence artificielle et de l\u2019Innovation num\u00e9rique, afin d\u2019\u00e9tudier le sujet de l\u2019intelligence artificielle.<\/em><\/p>\n<p><b>La s\u00e9natrice Gerba :<span>\u00a0<\/span><\/b>Monsieur le ministre, dans le cas de la Loi sur les langues officielles modernis\u00e9e qui garantit l\u2019\u00e9galit\u00e9 r\u00e9elle du fran\u00e7ais et de l\u2019anglais, quelles mesures le gouvernement met-il en place pour s\u2019assurer que les outils d\u2019intelligence artificielle utilis\u00e9s dans l\u2019administration f\u00e9d\u00e9rale offrent une qualit\u00e9 \u00e9quivalente dans les deux langues, sans d\u00e9savantager les francophones?<\/p>\n<p><b>M.\u00a0Solomon :<span>\u00a0<\/span><\/b>C\u2019est une question tr\u00e8s importante et essentielle pour notre pays, pour notre ministre et pour les technologies de l\u2019IA, puisque le gouvernement utilise la technologie. Il y a des r\u00e8gles \u00e0 cet \u00e9gard au Conseil du Tr\u00e9sor.<\/p>\n[<i>Traduction<\/i>]\n<p>Elles garantissent que nous respectons toujours la Loi sur les langues officielles, que nous nous assurons du plein acc\u00e8s des Canadiens francophones et que nous nous assurons que ces syst\u00e8mes sont disponibles de mani\u00e8re \u00e9gale en anglais.<\/p>\n<p>Cela se refl\u00e9tera \u00e9galement, une fois de plus, dans notre strat\u00e9gie nationale, mais il ne s\u2019agit pas seulement d\u2019une valeur fondamentale pour notre gouvernement; nous respectons scrupuleusement la Loi sur les langues officielles. C\u2019est essentiel; il ne s\u2019agit pas de s\u2019\u00e9carter de\u2026<\/p>\n<p><b>Le pr\u00e9sident :<span>\u00a0<\/span><\/b>Je vous remercie, monsieur le ministre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le S\u00e9nat s\u2019est form\u00e9 en comit\u00e9 pl\u00e9nier afin de recevoir l\u2019honorable Evan Solomon, c.p., d\u00e9put\u00e9, ministre de l\u2019Intelligence artificielle et de l\u2019Innovation num\u00e9rique, afin d\u2019\u00e9tudier le sujet de l\u2019intelligence artificielle. La s\u00e9natrice Gerba :\u00a0Monsieur le ministre, dans le cas de la Loi sur les langues officielles modernis\u00e9e qui garantit l\u2019\u00e9galit\u00e9 r\u00e9elle du fran\u00e7ais et de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[95],"tags":[],"senator_posts":[117],"class_list":["post-20951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-au-senat","senator_posts-l-hon-amina-gerba"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=20951"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/2004"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=20951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=20951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=20951"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=20951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}