{"id":20849,"date":"2026-03-25T16:38:23","date_gmt":"2026-03-25T20:38:23","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=20849"},"modified":"2026-03-30T16:39:49","modified_gmt":"2026-03-30T20:39:49","slug":"periode-des-questions-ministerielle-la-drepanocytose","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/periode-de-questions\/periode-des-questions-ministerielle-la-drepanocytose\/","title":{"rendered":"P\u00e9riode des questions minist\u00e9rielle : La dr\u00e9panocytose"},"content":{"rendered":"<p><iframe title=\"La s\u00e9natrice Gerba interroge la ministre Michel pendant la p\u00e9riode des questions minist\u00e9rielle (FR)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/zryVYEPJN44?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Amina Gerba :<span>\u00a0<\/span><\/b>Madame la ministre, la dr\u00e9panocytose est une maladie g\u00e9n\u00e9tique qui touche de mani\u00e8re disproportionn\u00e9e certaines populations, notamment d\u2019ascendance africaine et carib\u00e9enne. Elle demeure historiquement sous-diagnostiqu\u00e9e et insuffisamment prise en charge au Canada malgr\u00e9 des avanc\u00e9es r\u00e9centes en mati\u00e8re de d\u00e9pistage et de traitements.<\/p>\n<p>Quelle est la strat\u00e9gie f\u00e9d\u00e9rale actuelle pour am\u00e9liorer le d\u00e9pistage pr\u00e9coce, l\u2019acc\u00e8s aux traitements et le financement de la recherche sur cette maladie au Canada?<\/p>\n<p><b>L\u2019honorable Marjorie Michel, c.p., d\u00e9put\u00e9e, ministre de la Sant\u00e9 :<span>\u00a0<\/span><\/b>Je vous remercie, de votre question, s\u00e9natrice Gerba.<\/p>\n<p>Comme vous le savez, le d\u00e9pistage se fait d\u00e9j\u00e0 partout au pays pour tous les enfants qui naissent. En allant directement sur le terrain, je me rends compte que lors de l\u2019immigration de personnes afrodescendantes, ces gens arrivent souvent ici sans conna\u00eetre tout cela. Il faudrait donc que l\u2019on regarde comment faire le d\u00e9pistage en amont pour que les futurs parents sachent qu\u2019ils sont porteurs du g\u00e8ne.<\/p>\n<p>Pour ce qui est de la recherche, il est vrai que l\u2019on a besoin de faire plus de recherche. Il y en a d\u00e9j\u00e0 une qui est en cours. En collaboration avec les Instituts de recherche en sant\u00e9 du Canada, je suis \u00e0 regarder comment on peut effectivement examiner cela de plus pr\u00e8s.<\/p>\n<p>Cependant, cela reste quand m\u00eame de petites populations. Pour les populations noires, c\u2019est un gros enjeu. Ce sont de gros co\u00fbts aussi pour les familles et pour le syst\u00e8me de sant\u00e9, parce que les enfants sont constamment \u00e0 l\u2019h\u00f4pital.<\/p>\n<p>Aussi, on analyse la m\u00e9dication. Les traitements sont de plus en plus performants. Toutefois, actuellement, nous avons un enjeu de disponibilit\u00e9 de ces traitements au Canada, parce que nous repr\u00e9sentons un petit march\u00e9. On y travaille activement.<\/p>\n<p><b>La s\u00e9natrice Gerba :<span>\u00a0<\/span><\/b>En effet, ce sont de petites populations, mais il s\u2019agit d\u2019un co\u00fbt important pour la soci\u00e9t\u00e9. Le gouvernement envisage-t-il la mise en place d\u2019un cadre national sp\u00e9cifique ou d\u2019un plan d\u2019action? Au S\u00e9nat, nous avons d\u00e9j\u00e0 adopt\u00e9 un projet de loi \u00e0 cet effet. Est-ce que vous pensez que ce cadre national sera mis en place le plus t\u00f4t possible par le gouvernement?<\/p>\n<p><b>Mme\u00a0Michel :<span>\u00a0<\/span><\/b>Je sais que le projet de loi est \u00e0 la Chambre et qu\u2019il a \u00e9t\u00e9 parrain\u00e9 par un d\u00e9put\u00e9. Donc, on attend de voir ce qui se passera \u00e0 la Chambre. Je travaille avec le d\u00e9put\u00e9 l\u00e0-dessus.<\/p>\n<p>Si le projet de loi, ou je devrais dire quand le projet de loi sera adopt\u00e9 \u00e0 la Chambre, comme ministre de la Sant\u00e9, cela me donnera plus de leviers pour faire avancer les choses.<\/p>\n<p>Je suis au courant. M\u00eame au niveau de la formation, il faut absolument que les professionnels de la sant\u00e9 soient inform\u00e9s au sujet de cette maladie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Amina Gerba :\u00a0Madame la ministre, la dr\u00e9panocytose est une maladie g\u00e9n\u00e9tique qui touche de mani\u00e8re disproportionn\u00e9e certaines populations, notamment d\u2019ascendance africaine et carib\u00e9enne. Elle demeure historiquement sous-diagnostiqu\u00e9e et insuffisamment prise en charge au Canada malgr\u00e9 des avanc\u00e9es r\u00e9centes en mati\u00e8re de d\u00e9pistage et de traitements. Quelle est la strat\u00e9gie f\u00e9d\u00e9rale actuelle pour am\u00e9liorer le&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[97],"tags":[],"senator_posts":[117],"class_list":["post-20849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-periode-de-questions","senator_posts-l-hon-amina-gerba"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=20849"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/2036"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=20849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=20849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=20849"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=20849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}