{"id":20782,"date":"2026-03-24T12:34:04","date_gmt":"2026-03-24T16:34:04","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=20782"},"modified":"2026-03-25T12:36:55","modified_gmt":"2026-03-25T16:36:55","slug":"le-senateur-cardozo-interroge-annette-ryan-relativement-a-sa-nomination-au-poste-de-directrice-parlementaire-du-budget","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/le-senateur-cardozo-interroge-annette-ryan-relativement-a-sa-nomination-au-poste-de-directrice-parlementaire-du-budget\/","title":{"rendered":"Le s\u00e9nateur Cardozo interroge Annette Ryan relativement \u00e0 sa nomination au poste de directrice parlementaire du budget"},"content":{"rendered":"<p><iframe title=\"Le s\u00e9nateur Cardozo pose des questions \u00e0 Annette Ryan - 24 mars 2026 (source fran\u00e7aise)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/GGWH7WOLiwM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><!--StartFragment --><\/p>\n<p class=\"pf0\"><span class=\"cf0\"><em>Le S\u00e9nat s\u2019est form\u00e9 en comit\u00e9 pl\u00e9nier afin de recevoir Annette Ryan relativement \u00e0 sa nomination au poste de directrice parlementaire du budget.<\/em> <\/span><\/p>\n<p><!--EndFragment --><\/p>\n<p><b>Le s\u00e9nateur Cardozo :<span>\u00a0<\/span><\/b>Bienvenue, madame Ryan. Premi\u00e8rement, comment g\u00e9reriez-vous les d\u00e9saccords avec les minist\u00e8res et les organismes au sujet de l\u2019acc\u00e8s aux donn\u00e9es? C\u2019est un probl\u00e8me r\u00e9current.<\/p>\n<p>Deuxi\u00e8mement, en ce qui concerne les comptes publics, \u00e0 votre avis, en quoi les r\u00f4les du S\u00e9nat et de la Chambre des communes sont-ils diff\u00e9rents?<\/p>\n<p><b>Mme\u00a0Ryan :<span>\u00a0<\/span><\/b>Je vous remercie. Je pense que votre question sur l\u2019acc\u00e8s aux donn\u00e9es ressemble \u00e0 une autre question qui a \u00e9t\u00e9 pos\u00e9e plus t\u00f4t.<\/p>\n<p>Il est possible de tenir compte des situations individuelles et d\u2019\u00e9couter quelles sont les contraintes des gens en ce qui concerne l\u2019acc\u00e8s aux donn\u00e9es, par exemple s\u2019il s\u2019agit d\u2019une question de protection des renseignements personnels, de cybers\u00e9curit\u00e9, etc. Quelles sont les options pour surmonter ces obstacles afin que l\u2019analyse et le reste puissent avoir lieu? On peut faire des d\u00e9marches de bonne foi aupr\u00e8s des minist\u00e8res et essayer de r\u00e9gler ces probl\u00e8mes.<\/p>\n<p>Il y aura in\u00e9vitablement des domaines o\u00f9 ils ne fourniront pas de donn\u00e9es, de renseignements ou d\u2019autres \u00e9l\u00e9ments. Je pense que, dans ces situations, il faut appeler les choses par leur nom\u00a0: il s\u2019agit de r\u00e9pondre ou de ne pas r\u00e9pondre aux demandes du directeur parlementaire du budget, qui a une autorit\u00e9 l\u00e9gale. Il y a toujours moyen de pr\u00e9senter les choses de mani\u00e8re \u00e0 ce que le minist\u00e8re ou l\u2019organisme admette peut-\u00eatre le bien-fond\u00e9 d\u2019une pr\u00e9sentation des chiffres. Je pense qu\u2019il y a diff\u00e9rentes fa\u00e7ons d\u2019aborder la question.<\/p>\n<p>Si vous me le permettez, monsieur, puis-je vous demander de r\u00e9p\u00e9ter la deuxi\u00e8me question?<\/p>\n<p><b>Le s\u00e9nateur Cardozo :<span>\u00a0<\/span><\/b>Elle concernait la diff\u00e9rence entre le r\u00f4le de la Chambre des communes et celui du S\u00e9nat en ce qui a trait aux comptes publics.<\/p>\n<p><b>Mme\u00a0Ryan :<span>\u00a0<\/span><\/b>En tout respect, je tiens \u00e0 pr\u00e9ciser que je vais m\u2019informer sur ces diff\u00e9rents r\u00f4les et que j\u2019entends mettre en place des moyens pour soutenir les deux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le S\u00e9nat s\u2019est form\u00e9 en comit\u00e9 pl\u00e9nier afin de recevoir Annette Ryan relativement \u00e0 sa nomination au poste de directrice parlementaire du budget. Le s\u00e9nateur Cardozo :\u00a0Bienvenue, madame Ryan. Premi\u00e8rement, comment g\u00e9reriez-vous les d\u00e9saccords avec les minist\u00e8res et les organismes au sujet de l\u2019acc\u00e8s aux donn\u00e9es? C\u2019est un probl\u00e8me r\u00e9current. Deuxi\u00e8mement, en ce qui concerne&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[95],"tags":[],"senator_posts":[178],"class_list":["post-20782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-au-senat","senator_posts-l-hon-andrew-cardozo"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=20782"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/20782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/2046"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=20782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=20782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=20782"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=20782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}