{"id":19490,"date":"2025-10-29T16:08:55","date_gmt":"2025-10-29T20:08:55","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=19490"},"modified":"2025-10-30T10:00:31","modified_gmt":"2025-10-30T14:00:31","slug":"le-mois-de-lhistoire-des-femmes","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/declarations\/le-mois-de-lhistoire-des-femmes\/","title":{"rendered":"Le Mois de l\u2019histoire des femmes"},"content":{"rendered":"<p><iframe title=\"La s\u00e9natrice Hay parle du Mois de l\u2019histoire des femmes - 29 octobre 2025 (source fran\u00e7aise)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/lykOOBmIZTU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Katherine Hay :<span>\u00a0<\/span><\/b>Honorables s\u00e9nateurs, merci.<span>\u00a0<\/span><i>Meegwetch.<\/i><span>\u00a0<\/span>Je suis remplie de tant de gratitude. C\u2019est le Mois de l\u2019histoire des femmes, ce qui me rappelle que nous marchons dans les pas de v\u00e9ritables g\u00e9antes\u00a0: des femmes qui ont os\u00e9 r\u00eaver, prendre les r\u00eanes et changer le cours de l\u2019histoire du Canada.<\/p>\n<p>Il y a pr\u00e8s d\u2019un si\u00e8cle, Cairine Reay Mackay Wilson est devenue la premi\u00e8re s\u00e9natrice du Canada, l\u2019honorable s\u00e9natrice Wilson. Son portrait est accroch\u00e9 \u00e0 la salle de lecture du S\u00e9nat. Elle n\u2019a pas seulement marqu\u00e9 l\u2019histoire, elle a ouvert la voie \u00e0 notre pr\u00e9sence \u00e0 toutes dans cette enceinte.<\/p>\n<p>Je suis fi\u00e8re de servir aux c\u00f4t\u00e9s des femmes remarquables qui perp\u00e9tuent son h\u00e9ritage. Aux s\u00e9natrices Bernard, Senior, McCallum, Henkel, Osler, Mohamed, Coyle et Batters, \u00e0 madame la Pr\u00e9sidente Raymonde Gagn\u00e9 et \u00e0 toutes les femmes dans cette enceinte\u00a0: vous \u00eates des pionni\u00e8res et des mod\u00e8les pour moi. Je tenais \u00e0 vous le dire.<\/p>\n<p>Je vous rends hommage, \u00e0 vous et \u00e0 toutes les femmes qui nous ont ouvert la voie, qui ont refus\u00e9 d\u2019\u00eatre mises de c\u00f4t\u00e9, qui ont \u00e9lev\u00e9 les autres et qui ont surmont\u00e9 les obstacles.<\/p>\n<p>Pourtant, partout dans le monde, des droits autrefois consid\u00e9r\u00e9s comme s\u00fbrs font l\u2019objet de pressions. Je me souviens tr\u00e8s bien de l\u2019apr\u00e8s-midi du 22\u00a0juin\u00a02022, quand l\u2019arr\u00eat<span>\u00a0<\/span><i>Roe c. Wade<\/i><span>\u00a0<\/span>a \u00e9t\u00e9 invalid\u00e9. Je ne m\u2019attendais pas \u00e0 voir une telle chose de mon vivant, et j\u2019ai pleur\u00e9.<\/p>\n<p>La situation est plus s\u00fbre au Canada, mais cela d\u00e9pend de notre vigilance. Nous devons prot\u00e9ger le choix, la dignit\u00e9, l\u2019\u00e9galit\u00e9 et l\u2019\u00e9quit\u00e9. C\u2019est la bonne chose \u00e0 faire. Plus de 18\u00a0% des petites et moyennes entreprises appartiennent \u00e0 des femmes et ces entrepreneures contribuent chaque ann\u00e9e pour plus de 150 milliards de dollars \u00e0 l\u2019\u00e9conomie nationale. Les entreprises o\u00f9 le conseil d\u2019administration jouit d\u2019une diversit\u00e9 de genres sont 25\u00a0% plus susceptibles de d\u00e9passer les attentes. Les lieux de travail o\u00f9 des femmes sont \u00e0 la barre r\u00e9coltent de meilleurs r\u00e9sultats en mati\u00e8re d\u2019innovation, de gouvernance et de culture organisationnelle. Pourquoi ne pas miser sur les femmes?<\/p>\n<p>Alors que nous sommes orient\u00e9s vers l\u2019avenir, c\u2019est-\u00e0-dire la prochaine g\u00e9n\u00e9ration de jeunes filles et de femmes qui nous regardent aujourd\u2019hui, il nous incombe de ne pas les d\u00e9cevoir. En tant que citoyens, peu importe que nous nous identifiions comme femme, homme ou autre, nous avons non seulement le devoir de nourrir leur courage et leur confiance, mais aussi leur conviction qu\u2019elles peuvent fracasser le plafond de verre\u00a0\u2014 au lieu de s\u2019y river le nez. Il est de notre responsabilit\u00e9 de leur montrer les possibilit\u00e9s, et non les limites.<\/p>\n<p>Ma m\u00e8re, Jeanne Hay, a fait cela pour moi. Comme beaucoup d\u2019autres avant elle, ma m\u00e8re est la preuve vivante que chaque femme est port\u00e9e par la force d\u2019une autre qui a ouvert la voie.<\/p>\n<p>Le Mois de l\u2019histoire des femmes ne vise pas seulement \u00e0 reconna\u00eetre le chemin parcouru, mais aussi l\u2019histoire qui se fa\u00e7onne au jour le jour, sur laquelle prend appui l\u2019avenir de chacun d\u2019entre nous.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Katherine Hay :\u00a0Honorables s\u00e9nateurs, merci.\u00a0Meegwetch.\u00a0Je suis remplie de tant de gratitude. C\u2019est le Mois de l\u2019histoire des femmes, ce qui me rappelle que nous marchons dans les pas de v\u00e9ritables g\u00e9antes\u00a0: des femmes qui ont os\u00e9 r\u00eaver, prendre les r\u00eanes et changer le cours de l\u2019histoire du Canada. Il y a pr\u00e8s d\u2019un si\u00e8cle,&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2000,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[99],"tags":[],"senator_posts":[196],"class_list":["post-19490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-declarations","senator_posts-l-hon-katherine-hay"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/19490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=19490"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/19490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/2000"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=19490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=19490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=19490"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=19490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}