{"id":19466,"date":"2025-10-28T13:06:42","date_gmt":"2025-10-28T17:06:42","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=19466"},"modified":"2025-10-29T13:08:46","modified_gmt":"2025-10-29T17:08:46","slug":"periode-des-questions-ministerielle-la-nation-dakota-de-whitecap-wapaha-ska-dakota-oyate-2","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/periode-de-questions\/periode-des-questions-ministerielle-la-nation-dakota-de-whitecap-wapaha-ska-dakota-oyate-2\/","title":{"rendered":"P\u00e9riode des questions minist\u00e9rielle : La Nation dakota de Whitecap \/ Wapaha Ska Dakota Oyate"},"content":{"rendered":"<p><iframe title=\"Le s\u00e9nateur Klyne interroge la ministre Gull-Masty sur la Nation dakota de Whitecap - 28 oct 25 (FR)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/4IDB-aDEXuM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Marty Klyne :<span>\u00a0<\/span><\/b>Madame la ministre, bienvenue. La semaine derni\u00e8re, la Nation dakota de Whitecap a recommand\u00e9 deux amendements au projet de loi\u00a0S-2 lors de notre r\u00e9union du Comit\u00e9 s\u00e9natorial permanent des peuples autochtones. L\u2019un d\u2019eux est une solution provisoire \u00e0 l\u2019exclusion apr\u00e8s la deuxi\u00e8me g\u00e9n\u00e9ration, qui menace la survie de nombreuses Premi\u00e8res Nations et exclut certaines personnes de leurs communaut\u00e9s. La Nation dakota de Whitecap propose de permettre aux Premi\u00e8res Nations de conf\u00e9rer de leur propre autorit\u00e9 le statut irr\u00e9vocable pr\u00e9vu au paragraphe\u00a06(2) \u00e0 une personne ayant au moins un parent b\u00e9n\u00e9ficiant de ce statut ainsi qu\u2019un lien avec la communaut\u00e9.<\/p>\n<p>Cette solution viable respecterait les principes d\u2019autod\u00e9termination, de lien entre le patrimoine et le statut et de lien avec la communaut\u00e9. Elle comporte \u00e9galement un mod\u00e8le d\u2019adh\u00e9sion volontaire, puisque les Premi\u00e8res Nations devraient choisir d\u2019exercer leur autorit\u00e9 pour conf\u00e9rer le statut.<\/p>\n<p>Pourriez-vous envisager cet amendement provisoire comme une solution imm\u00e9diate pour rem\u00e9dier \u00e0 des pr\u00e9judices urgents? Pourriez-vous offrir des pr\u00e9cisions \u00e0 cet \u00e9gard?<\/p>\n<p><b>L\u2019honorable Mandy Gull-Masty, c.p., d\u00e9put\u00e9e, ministre des Services aux Autochtones :<span>\u00a0<\/span><\/b>Merci. Il est essentiel de consulter les Premi\u00e8res Nations au sujet de l\u2019exclusion apr\u00e8s la deuxi\u00e8me g\u00e9n\u00e9ration, car, m\u00eame si le chef Darcy Bear et la Premi\u00e8re Nation de Whitecap estiment que cela pourrait \u00eatre une solution pour eux, ce n\u2019est peut-\u00eatre pas une solution bien d\u2019autres groupes. J\u2019ai oubli\u00e9 le terme qu\u2019on m\u2019a fourni pour parler des cons\u00e9quences possibles, mais cela pourrait entra\u00eener des cons\u00e9quences qui n\u2019\u00e9taient pas pr\u00e9vues au moment de prendre une d\u00e9cision. Le terme va me revenir \u00e0 l\u2019esprit d\u00e8s que je serai partie. Quoi qu\u2019il en soit, une d\u00e9cision peut \u00eatre tr\u00e8s lourde de cons\u00e9quences pour certaines Premi\u00e8res Nations.<\/p>\n<p>\u00c0 mon avis, la port\u00e9e de cette consultation permettra aux collectivit\u00e9s de choisir leur solution. C\u2019est un dossier complexe. Il n\u2019y a pas de solution universelle. Nous devons rencontrer les communaut\u00e9s et les laisser trouver leur solution. On ne peut pas s\u2019en tenir \u00e0 un seul processus et tenter de l\u2019appliquer \u00e0 toutes les situations.<\/p>\n<p>Encore une fois, en tant que ministre, je ne peux pas contourner le processus de consultation. J\u2019ai l\u2019obligation de consulter. Non seulement je suis tenue de le faire, mais, en tant qu\u2019Autochtone, j\u2019ai aussi demand\u00e9 au gouvernement de le respecter, mais aussi de respecter cette obligation ainsi que le principe du consentement pr\u00e9alable, donn\u00e9 librement et en connaissance de cause et la D\u00e9claration des Nations unies sur les droits des peuples autochtones. Je maintiens cette position en tant que ministre.<\/p>\n<p><b>Le s\u00e9nateur Klyne :<span>\u00a0<\/span><\/b>Madame la ministre, le deuxi\u00e8me amendement propos\u00e9 par la nation de Whitecap concerne le transfert des avantages pr\u00e9vus par les trait\u00e9s. \u00c0 l\u2019heure actuelle, quand une personne appartenant \u00e0 une nation signataire d\u2019un trait\u00e9 num\u00e9rot\u00e9 est transf\u00e9r\u00e9e \u00e0 une nation signataire d\u2019un trait\u00e9 non num\u00e9rot\u00e9, comme la Nation dakota, elle perd les avantages pr\u00e9vus par le trait\u00e9. Cependant, nulle part dans les trait\u00e9s il n\u2019est indiqu\u00e9 que le mariage ou le transfert annule ces avantages l\u00e9gitimes, qui sont essentiellement des h\u00e9ritages.<\/p>\n<p>Pourriez-vous envisager un amendement afin de pr\u00e9ciser que ces avantages ne devraient pas se perdre \u00e0 la suite d\u2019un transfert et, au contraire, consid\u00e9rer les droits inh\u00e9rents \u00e0 nos trait\u00e9s comme r\u00e9ponse?<\/p>\n<p><b>Mme\u00a0Gull-Masty :<span>\u00a0<\/span><\/b>Les relations avec la Couronne rel\u00e8vent du domaine de comp\u00e9tence de ma coll\u00e8gue la ministre Alty. J\u2019ai beaucoup de respect pour elle et j\u2019appr\u00e9cie grandement notre collaboration. Nous estimons toutes deux que lorsque de tels ajustements sont n\u00e9cessaires, ils doivent \u00eatre dict\u00e9s par la communaut\u00e9.<\/p>\n<p>Les consultations sur le seuil de la deuxi\u00e8me g\u00e9n\u00e9ration font partie\u00a0du travail que nous effectuons autour de la question du statut. Une partie\u00a0de son travail doit s\u2019aligner sur cette question. Pour moi, la d\u00e9marche qui s\u2019impose, c\u2019est de prendre le temps de v\u00e9rifier que cet\u00a0alignement correspond bien \u00e0 ce que les communaut\u00e9s nous demandent de faire. C\u2019est pour cette raison que nous r\u00e9affirmons une fois de plus l\u2019importance du processus de consultation avec les d\u00e9tenteurs de droits.<\/p>\n<p><b>Son Honneur la Pr\u00e9sidente :<span>\u00a0<\/span><\/b>Honorables s\u00e9nateurs, la p\u00e9riode des questions est termin\u00e9e.<\/p>\n<p>Je suis certaine que vous vous joindrez \u00e0 moi pour remercier la ministre Gull-Masty de s\u2019\u00eatre jointe \u00e0 nous aujourd\u2019hui. Merci.<\/p>\n<p><b>Des voix :<span>\u00a0<\/span><\/b>Bravo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Marty Klyne :\u00a0Madame la ministre, bienvenue. La semaine derni\u00e8re, la Nation dakota de Whitecap a recommand\u00e9 deux amendements au projet de loi\u00a0S-2 lors de notre r\u00e9union du Comit\u00e9 s\u00e9natorial permanent des peuples autochtones. L\u2019un d\u2019eux est une solution provisoire \u00e0 l\u2019exclusion apr\u00e8s la deuxi\u00e8me g\u00e9n\u00e9ration, qui menace la survie de nombreuses Premi\u00e8res Nations et&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[97],"tags":[],"senator_posts":[34],"class_list":["post-19466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-periode-de-questions","senator_posts-l-hon-marty-klyne"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/19466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=19466"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/19466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/1946"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=19466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=19466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=19466"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=19466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}