{"id":19395,"date":"2025-10-09T11:43:45","date_gmt":"2025-10-09T15:43:45","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=19395"},"modified":"2025-10-10T11:46:25","modified_gmt":"2025-10-10T15:46:25","slug":"joyce-echaquan-2","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/declarations\/joyce-echaquan-2\/","title":{"rendered":"Joyce Echaquan"},"content":{"rendered":"<p><iframe title=\"La s\u00e9natrice Audette parle de Joyce Echaquan - 9 octobre 2025 (source fran\u00e7aise)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/Bwami843Wk0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Mich\u00e8le Audette :<span>\u00a0<\/span><\/b>[<i>Note de la r\u00e9daction\u00a0:<span>\u00a0<\/span><\/i><i>La s\u00e9natrice<span>\u00a0<\/span><\/i><i>Audette s\u2019exprime<span>\u00a0<\/span><\/i><i>en innu-aimun<\/i>.]\n<p>Je tiens \u00e0 remercier le peuple anishinabe de nous accueillir tous les jours. Je remercie \u00e9galement les gens qui viennent de plusieurs territoires.<\/p>\n<p>Je prends la parole aujourd\u2019hui pour rappeler un petit bout d\u2019histoire\u00a0: depuis des mill\u00e9naires, l\u2019automne, c\u2019est le moment o\u00f9 l\u2019on est d\u00e9j\u00e0 install\u00e9, apr\u00e8s un long portage dans nos territoires.<\/p>\n<p>Alors, c\u2019\u00e9tait avec beaucoup de force et de r\u00e9silience, mais depuis des d\u00e9cennies, l\u2019automne est charg\u00e9 d\u2019\u00e9motions, de souvenirs, de comm\u00e9morations, de douleurs, mais aussi de gu\u00e9rison et d\u2019espoir. Un petit rappel pour Joyce Echaquan, le 28 septembre, qui nous a quitt\u00e9s dans des circonstances atroces et inacceptables.<\/p>\n<p>Merci, Carol et Diane, de nous rappeler que la vie doit continuer, mais nous, vos alli\u00e9s, hommes et femmes, devons marcher \u00e0 vos c\u00f4t\u00e9s.<\/p>\n<p>Le 30 septembre, pour nos m\u00e8res, nos p\u00e8res, nos oncles, pour les gens qui nous ont laiss\u00e9s aussi dans des circonstances atroces, la r\u00e9conciliation est collective, qu\u2019elle soit l\u00e9gislative, \u00e9conomique et ainsi de suite, et elle apporte la gu\u00e9rison.<\/p>\n<p>Je dis \u00e0 toutes ces personnes qu\u2019on retrouve tranquillement, gr\u00e2ce \u00e0 la technologie, mais surtout gr\u00e2ce \u00e0 la force de la parole des gens, qu\u2019elles ont vraiment exist\u00e9.<\/p>\n<p>Tous ceux et celles qui ont de la difficult\u00e9 \u00e0 croire ces grandes v\u00e9rit\u00e9s, je vous invite \u00e0 venir vivre chez moi pendant un mois pour \u00e9veiller vos cinq sens \u00e0 une histoire et \u00e0 une force collectives.<\/p>\n<p>Le 4 octobre, nous nous souviendrons aussi de nos s\u0153urs vol\u00e9es, de nos filles. Parce qu\u2019elles \u00e9taient femmes autochtones, elles ont \u00e9t\u00e9 cibl\u00e9es pendant des si\u00e8cles, pas juste depuis quelque temps, mais pendant trop longtemps.<\/p>\n<p>Un devoir de m\u00e9moire aussi pour nos s\u0153urs d\u2019esprit. Je vous dis merci de nous avoir guid\u00e9s pendant une enqu\u00eate nationale et de nous avoir rappel\u00e9 qu\u2019il y a des appels \u00e0 la justice qu\u2019on doit honorer. Je vous embrasse dans le monde du caribou et nous sommes plusieurs \u00e0 marcher \u00e0 vos c\u00f4t\u00e9s, merci beaucoup.<\/p>\n[<i>Traduction<\/i>]\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Mich\u00e8le Audette :\u00a0[Note de la r\u00e9daction\u00a0:\u00a0La s\u00e9natrice\u00a0Audette s\u2019exprime\u00a0en innu-aimun.] Je tiens \u00e0 remercier le peuple anishinabe de nous accueillir tous les jours. Je remercie \u00e9galement les gens qui viennent de plusieurs territoires. Je prends la parole aujourd\u2019hui pour rappeler un petit bout d\u2019histoire\u00a0: depuis des mill\u00e9naires, l\u2019automne, c\u2019est le moment o\u00f9 l\u2019on est d\u00e9j\u00e0&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[99],"tags":[],"senator_posts":[172],"class_list":["post-19395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-declarations","senator_posts-l-hon-michele-audette"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/19395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=19395"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/19395\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/1892"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=19395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=19395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=19395"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=19395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}