{"id":18897,"date":"2025-06-25T17:08:50","date_gmt":"2025-06-25T21:08:50","guid":{"rendered":"https:\/\/theprogressives.ca\/?p=18897"},"modified":"2025-06-26T09:57:40","modified_gmt":"2025-06-26T13:57:40","slug":"lhonorable-daniele-henkel-felicitations-a-loccasion-de-sa-nomination-a-titre-de-capitaine-honoraire-de-la-garde-cotiere-canadienne","status":"publish","type":"post","link":"https:\/\/theprogressives.ca\/fr\/au-senat\/declarations\/lhonorable-daniele-henkel-felicitations-a-loccasion-de-sa-nomination-a-titre-de-capitaine-honoraire-de-la-garde-cotiere-canadienne\/","title":{"rendered":"L&rsquo;honorable Dani\u00e8le Henkel\u2014F\u00e9licitations \u00e0 l&rsquo;occasion de sa nomination \u00e0 titre de capitaine honoraire de la Garde c\u00f4ti\u00e8re canadienne"},"content":{"rendered":"<p><iframe title=\"La s\u00e9natrice Gerba f\u00e9licite la s\u00e9natrice Henkel - 25 juin 2025 (source fran\u00e7aise)\" width=\"640\" height=\"360\" data-src=\"https:\/\/www.youtube.com\/embed\/oshNcpluLXc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe><\/p>\n<p><b>L\u2019honorable Amina Gerba :<span>\u00a0<\/span><\/b>Honorables s\u00e9nateurs, je prends la parole aujourd\u2019hui avec une grande fiert\u00e9 pour souligner la nomination de notre coll\u00e8gue la s\u00e9natrice Dani\u00e8le Henkel \u00e0 titre de capitaine honoraire de la Garde c\u00f4ti\u00e8re canadienne.<\/p>\n<p>Premi\u00e8re femme \u00e0 occuper cette fonction, elle incarne un symbole fort d\u2019espoir et de progr\u00e8s. Sa nomination envoie un message clair\u00a0: les femmes ont leur place dans toutes les sph\u00e8res du leadership, y compris dans les institutions maritimes.<\/p>\n<p>Les capitaines honoraires ont pour mission de tisser des liens entre la Garde c\u00f4ti\u00e8re et la soci\u00e9t\u00e9 civile.<\/p>\n<p>Par leur engagement, ils contribuent \u00e0 faire rayonner les valeurs, les missions et le d\u00e9vouement de celles et ceux qui veillent chaque jour sur nos eaux.<\/p>\n<p>Dans un pays bord\u00e9 par trois oc\u00e9ans, la Garde c\u00f4ti\u00e8re est bien plus qu\u2019un service\u00a0: elle est un pilier de notre souverainet\u00e9, un garant de notre s\u00e9curit\u00e9, un soutien vital pour nos communaut\u00e9s c\u00f4ti\u00e8res.<\/p>\n<p>Femme d\u2019affaires accomplie, philanthrope engag\u00e9e et lieutenante-colonelle honoraire du R\u00e9giment de Maisonneuve, la s\u00e9natrice Henkel incarne le courage, la r\u00e9silience et l\u2019inspiration. Elle sait naviguer avec gr\u00e2ce dans les temp\u00eates et guider avec humilit\u00e9. Son parcours est un phare pour celles et ceux qui r\u00eavent de servir, d\u2019entreprendre et de b\u00e2tir un avenir meilleur pour nos communaut\u00e9s.<\/p>\n<p>S\u00e9natrice Henkel, en vous accueillant dans ses rangs, la Garde c\u00f4ti\u00e8re s\u2019enrichit d\u2019une voix forte et d\u2019un c\u0153ur engag\u00e9. C\u2019est tout le Canada qui s\u2019en trouve honor\u00e9.<\/p>\n<p>Au nom du Groupe progressiste du S\u00e9nat et de nous tous dans cette Chambre, je vous offre nos plus sinc\u00e8res f\u00e9licitations et nos v\u0153ux de succ\u00e8s dans cette nouvelle travers\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019honorable Amina Gerba :\u00a0Honorables s\u00e9nateurs, je prends la parole aujourd\u2019hui avec une grande fiert\u00e9 pour souligner la nomination de notre coll\u00e8gue la s\u00e9natrice Dani\u00e8le Henkel \u00e0 titre de capitaine honoraire de la Garde c\u00f4ti\u00e8re canadienne. Premi\u00e8re femme \u00e0 occuper cette fonction, elle incarne un symbole fort d\u2019espoir et de progr\u00e8s. Sa nomination envoie un message&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"footnotes":""},"categories":[99],"tags":[],"senator_posts":[117],"class_list":["post-18897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-declarations","senator_posts-l-hon-amina-gerba"],"acf":[],"_links":{"self":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/18897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/comments?post=18897"}],"version-history":[{"count":0,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/posts\/18897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media\/1996"}],"wp:attachment":[{"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/media?parent=18897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/categories?post=18897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/tags?post=18897"},{"taxonomy":"senator_posts","embeddable":true,"href":"https:\/\/theprogressives.ca\/fr\/wp-json\/wp\/v2\/senator_posts?post=18897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}